{"id":67,"count":1,"description":"Celulares de las Mejores Marcas: Samsung, Xioami, Huawei, Motorola,Apple","link":"https:\/\/extremecomputadoras.com\/portal\/categoria-producto\/celulares\/","name":"Celulares","slug":"celulares","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/extremecomputadoras.com\/portal\/wp-json\/wp\/v2\/product_cat\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/extremecomputadoras.com\/portal\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/extremecomputadoras.com\/portal\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/extremecomputadoras.com\/portal\/wp-json\/wp\/v2\/product?product_cat=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}